{"id":1052,"count":1,"description":"","link":"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/","name":"risk of total loss","slug":"risk-of-total-loss","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>risk of total loss Archive - Finkbeiner Kanzlei<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"risk of total loss Archive - Finkbeiner Kanzlei\" \/>\n<meta property=\"og:url\" content=\"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/\" \/>\n<meta property=\"og:site_name\" content=\"Finkbeiner Kanzlei\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/tag\\\/risk-of-total-loss\\\/\",\"url\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/tag\\\/risk-of-total-loss\\\/\",\"name\":\"risk of total loss Archive - Finkbeiner Kanzlei\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/tag\\\/risk-of-total-loss\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/tag\\\/risk-of-total-loss\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"risk of total loss\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/\",\"name\":\"Finkbeiner Kanzlei\",\"description\":\"Anwaltskanzlei f\u00fcr Wirtschaftsrecht, Insolvenzrecht und Prozessrecht\",\"publisher\":{\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/#\\\/schema\\\/person\\\/82fb4d962f5edb406c94928cf461bbde\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":[\"Person\",\"Organization\"],\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/en\\\/#\\\/schema\\\/person\\\/82fb4d962f5edb406c94928cf461bbde\",\"name\":\"Claudius Finkbeiner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/5C66DF9B-A999-44A1-969D-4233F47A5B77-96x96.jpg\",\"url\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/5C66DF9B-A999-44A1-969D-4233F47A5B77-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/5C66DF9B-A999-44A1-969D-4233F47A5B77-96x96.jpg\",\"caption\":\"Claudius Finkbeiner\"},\"logo\":{\"@id\":\"https:\\\/\\\/finkbeiner-kanzlei.de\\\/wp-content\\\/uploads\\\/2017\\\/12\\\/5C66DF9B-A999-44A1-969D-4233F47A5B77-96x96.jpg\"},\"description\":\"Herr Finkbeiner ist seit dem Jahr 2009 als Rechtsanwalt t\u00e4tig. Sein Schwerpunkt liegt im wirtschaftsrechtlichen Bereich, insbesondere im Insolvenz-, Vertrags- und Gesellschaftsrecht sowie im Vergaberecht. Herr Finkbeiner ber\u00e4t und vertritt Unternehmen in der Krise, ebenso wie Gesch\u00e4ftsf\u00fchrer, Gl\u00e4ubiger und andere Beteiligte im Insolvenzverfahren und gegen Insolvenzverwalter. Herr Finkbeiner ist ein erfahrener Prozessanwalt im Wirtschaftsrecht und Verteidiger in Wirtschaftsstrafsachen.\",\"sameAs\":[\"https:\\\/\\\/www.anwalt-finkbeiner.de\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"risk of total loss Archive - Finkbeiner Kanzlei","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/","og_locale":"en_US","og_type":"article","og_title":"risk of total loss Archive - Finkbeiner Kanzlei","og_url":"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/","og_site_name":"Finkbeiner Kanzlei","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/","url":"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/","name":"risk of total loss Archive - Finkbeiner Kanzlei","isPartOf":{"@id":"https:\/\/finkbeiner-kanzlei.de\/en\/#website"},"breadcrumb":{"@id":"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/finkbeiner-kanzlei.de\/en\/tag\/risk-of-total-loss\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/finkbeiner-kanzlei.de\/en\/"},{"@type":"ListItem","position":2,"name":"risk of total loss"}]},{"@type":"WebSite","@id":"https:\/\/finkbeiner-kanzlei.de\/en\/#website","url":"https:\/\/finkbeiner-kanzlei.de\/en\/","name":"Finkbeiner Kanzlei","description":"Anwaltskanzlei f\u00fcr Wirtschaftsrecht, Insolvenzrecht und Prozessrecht","publisher":{"@id":"https:\/\/finkbeiner-kanzlei.de\/en\/#\/schema\/person\/82fb4d962f5edb406c94928cf461bbde"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/finkbeiner-kanzlei.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":["Person","Organization"],"@id":"https:\/\/finkbeiner-kanzlei.de\/en\/#\/schema\/person\/82fb4d962f5edb406c94928cf461bbde","name":"Claudius Finkbeiner","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/finkbeiner-kanzlei.de\/wp-content\/uploads\/2017\/12\/5C66DF9B-A999-44A1-969D-4233F47A5B77-96x96.jpg","url":"https:\/\/finkbeiner-kanzlei.de\/wp-content\/uploads\/2017\/12\/5C66DF9B-A999-44A1-969D-4233F47A5B77-96x96.jpg","contentUrl":"https:\/\/finkbeiner-kanzlei.de\/wp-content\/uploads\/2017\/12\/5C66DF9B-A999-44A1-969D-4233F47A5B77-96x96.jpg","caption":"Claudius Finkbeiner"},"logo":{"@id":"https:\/\/finkbeiner-kanzlei.de\/wp-content\/uploads\/2017\/12\/5C66DF9B-A999-44A1-969D-4233F47A5B77-96x96.jpg"},"description":"Herr Finkbeiner ist seit dem Jahr 2009 als Rechtsanwalt t\u00e4tig. Sein Schwerpunkt liegt im wirtschaftsrechtlichen Bereich, insbesondere im Insolvenz-, Vertrags- und Gesellschaftsrecht sowie im Vergaberecht. Herr Finkbeiner ber\u00e4t und vertritt Unternehmen in der Krise, ebenso wie Gesch\u00e4ftsf\u00fchrer, Gl\u00e4ubiger und andere Beteiligte im Insolvenzverfahren und gegen Insolvenzverwalter. Herr Finkbeiner ist ein erfahrener Prozessanwalt im Wirtschaftsrecht und Verteidiger in Wirtschaftsstrafsachen.","sameAs":["https:\/\/www.anwalt-finkbeiner.de"]}]}},"_links":{"self":[{"href":"https:\/\/finkbeiner-kanzlei.de\/en\/wp-json\/wp\/v2\/tags\/1052","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/finkbeiner-kanzlei.de\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/finkbeiner-kanzlei.de\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/finkbeiner-kanzlei.de\/en\/wp-json\/wp\/v2\/posts?tags=1052"},{"href":"https:\/\/finkbeiner-kanzlei.de\/en\/wp-json\/wp\/v2\/pages?tags=1052"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}